{"id":64578,"date":"2022-01-23T09:06:19","date_gmt":"2022-01-23T11:06:19","guid":{"rendered":"http:\/\/www.lorena.sp.gov.br\/wordpress\/?p=64578"},"modified":"2022-01-24T09:09:38","modified_gmt":"2022-01-24T11:09:38","slug":"boletim-coronavirus-23-de-janeiro-de-2022","status":"publish","type":"post","link":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/2022\/01\/23\/boletim-coronavirus-23-de-janeiro-de-2022\/","title":{"rendered":"BOLETIM CORONAV\u00cdRUS 23 DE JANEIRO DE 2022"},"content":{"rendered":"<p>Painel de Evolu\u00e7\u00e3o Covid-19 deste domingo (23\/01)\u2063\u2063<br \/>\n\u2063\u2063<br \/>\nSe voc\u00ea ainda n\u00e3o se vacinou, confira o cronograma completo atrav\u00e9s do site da Prefeitura, pelo link: https:\/\/cutt.ly\/MWvcILT\u2063\u2063<br \/>\n\u2063\u2063<br \/>\nA contagem de pacientes em tratamento considera as interna\u00e7\u00f5es na Santa Casa, Unimed e tamb\u00e9m de pessoas residentes em Lorena que est\u00e3o internadas em hospitais de outros munic\u00edpios. Logo, o total de casos em tratamento n\u00e3o \u00e9 igual \u00e0 soma das interna\u00e7\u00f5es em hospitais municipais.\u2063\u2063<br \/>\n\u2063\u2063<br \/>\nH\u00e1 tamb\u00e9m pacientes que aguardam o resultado dos exames de confirma\u00e7\u00e3o da Covid, que n\u00e3o s\u00e3o somados nesta contagem, segundo a Secretaria de Sa\u00fade.\u2063\u2063<br \/>\n\u2063\u2063<br \/>\nN\u00e3o h\u00e1 nenhum novo \u00f3bito confirmado e nenhum como suspeito, segundo o boletim da Vigil\u00e2ncia Epidemiol\u00f3gica deste domingo (23\/01)\u2063\u2063.\u2063<br \/>\nObs.: A vigil\u00e2ncia epidemiol\u00f3gica para evitar maiores transtornos, p\u00e2nico ou confus\u00e3o em torno do processo de vacina\u00e7\u00e3o decide previamente n\u00e3o divulgar dados espec\u00edficos sobre o calend\u00e1rio vacinal das v\u00edtimas.<br \/>\nA Secretaria de Sa\u00fade salienta ainda a extrema import\u00e2ncia de que cada mun\u00edcipe siga seu calend\u00e1rio vacinal, completando todas as doses dispon\u00edveis para cada faixa et\u00e1ria.<br \/>\n\u2063\u2063<br \/>\nA Sa\u00fade, preservando a intimidade dos familiares que atravessam o luto, n\u00e3o divulgar\u00e1 o perfil das v\u00edtimas.<\/p>\n<p><a href=\"http:\/\/www.lorena.sp.gov.br\/wordpress\/wp-content\/uploads\/2022\/01\/Boletim-Covid-23-01-2022.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-64579\" src=\"http:\/\/www.lorena.sp.gov.br\/wordpress\/wp-content\/uploads\/2022\/01\/Boletim-Covid-23-01-2022.png\" alt=\"Boletim Covid 23-01-2022\" width=\"800\" height=\"828\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Painel de Evolu\u00e7\u00e3o Covid-19 deste domingo (23\/01)\u2063\u2063 \u2063\u2063 Se voc\u00ea ainda n\u00e3o se vacinou, confira o cronograma completo atrav\u00e9s do site da Prefeitura, pelo link: https:\/\/cutt.ly\/MWvcILT\u2063\u2063 \u2063\u2063 A contagem de pacientes em tratamento considera as interna\u00e7\u00f5es na Santa Casa, Unimed e tamb\u00e9m de pessoas residentes em Lorena que est\u00e3o internadas em hospitais de outros munic\u00edpios.<\/p>\n<div class=\"read-more\"><a href=\"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/2022\/01\/23\/boletim-coronavirus-23-de-janeiro-de-2022\/\" title=\"Read More\">Read More<\/a><\/div>\n","protected":false},"author":2,"featured_media":64580,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[127,128,13],"tags":[],"class_list":{"0":"post-64578","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-boletim-coronavirus","8":"category-coronavirus","9":"category-saude"},"_links":{"self":[{"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/posts\/64578"}],"collection":[{"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/comments?post=64578"}],"version-history":[{"count":1,"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/posts\/64578\/revisions"}],"predecessor-version":[{"id":64581,"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/posts\/64578\/revisions\/64581"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/media\/64580"}],"wp:attachment":[{"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/media?parent=64578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/categories?post=64578"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/tags?post=64578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}