{"id":62740,"date":"2021-08-31T08:56:07","date_gmt":"2021-08-31T11:56:07","guid":{"rendered":"http:\/\/www.lorena.sp.gov.br\/wordpress\/?p=62740"},"modified":"2021-08-31T08:56:07","modified_gmt":"2021-08-31T11:56:07","slug":"revitalizacao-e-criacao-de-sinalizacoes-de-transito-em-lorena","status":"publish","type":"post","link":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/2021\/08\/31\/revitalizacao-e-criacao-de-sinalizacoes-de-transito-em-lorena\/","title":{"rendered":"Revitaliza\u00e7\u00e3o e cria\u00e7\u00e3o de sinaliza\u00e7\u00f5es de tr\u00e2nsito em Lorena"},"content":{"rendered":"<p>A Secretaria de Tr\u00e2nsito e Transportes est\u00e1 realizando a revitaliza\u00e7\u00e3o das sinaliza\u00e7\u00f5es de tr\u00e2nsito em alguns bairros da cidade, a fim de promover um tr\u00e2nsito mais seguro e manter a manuten\u00e7\u00e3o em dia.<\/p>\n<p>Os bairros contemplados foram o Centro e Vila Z\u00e9lia.<\/p>\n<p>#lorenanaopara #revitalizacao #transito #governodeoportunidades<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62741\" src=\"http:\/\/www.lorena.sp.gov.br\/wordpress\/wp-content\/uploads\/2021\/08\/revitalizacao-04.png\" alt=\"revitalizacao-04\" width=\"800\" height=\"800\" srcset=\"http:\/\/www.lorena.sp.gov.br\/wordpress\/wp-content\/uploads\/2021\/08\/revitalizacao-04.png 800w, http:\/\/www.lorena.sp.gov.br\/wordpress\/wp-content\/uploads\/2021\/08\/revitalizacao-04-150x150.png 150w, http:\/\/www.lorena.sp.gov.br\/wordpress\/wp-content\/uploads\/2021\/08\/revitalizacao-04-150x150@2x.png 300w, http:\/\/www.lorena.sp.gov.br\/wordpress\/wp-content\/uploads\/2021\/08\/revitalizacao-04-300x300@2x.png 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Tr\u00e2nsito e Transportes est\u00e1 realizando a revitaliza\u00e7\u00e3o das sinaliza\u00e7\u00f5es de tr\u00e2nsito em alguns bairros da cidade, a fim de promover um tr\u00e2nsito mais seguro e manter a manuten\u00e7\u00e3o em dia. Os bairros contemplados foram o Centro e Vila Z\u00e9lia. #lorenanaopara #revitalizacao #transito #governodeoportunidades &nbsp; &nbsp;<\/p>\n","protected":false},"author":2,"featured_media":62742,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":{"0":"post-62740","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-secretaria-transito"},"_links":{"self":[{"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/posts\/62740"}],"collection":[{"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/comments?post=62740"}],"version-history":[{"count":1,"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/posts\/62740\/revisions"}],"predecessor-version":[{"id":62743,"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/posts\/62740\/revisions\/62743"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/media\/62742"}],"wp:attachment":[{"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/media?parent=62740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/categories?post=62740"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/tags?post=62740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}