{"id":57564,"date":"2020-07-30T16:50:13","date_gmt":"2020-07-30T19:50:13","guid":{"rendered":"http:\/\/www.lorena.sp.gov.br\/wordpress\/?p=57564"},"modified":"2020-07-30T16:50:42","modified_gmt":"2020-07-30T19:50:42","slug":"prefeitura-estende-quarentena-ate-10-de-agosto","status":"publish","type":"post","link":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/2020\/07\/30\/prefeitura-estende-quarentena-ate-10-de-agosto\/","title":{"rendered":"Prefeitura estende quarentena at\u00e9 10 de agosto"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\">O Prefeito F\u00e1bio Marcondes assinou nesta quinta-feira (30), o <span style=\"color: #3366ff;\"><a style=\"color: #3366ff;\" href=\"http:\/\/www.lorena.sp.gov.br\/wordpress\/wp-content\/uploads\/2020\/07\/Decreto-7466.2020.pdf\" target=\"_blank\">Decreto Municipal 7466\u00a0de 30 de julho 2020<\/a><\/span> que estende at\u00e9 10 de agosto o per\u00edodo de quarentena em preven\u00e7\u00e3o ao coronav\u00edrus. O decreto refor\u00e7a que n\u00e3o h\u00e1 nenhuma altera\u00e7\u00e3o nos par\u00e2metros de isolamento social e que estes seguem as decis\u00f5es do Plano SP.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Divulgado no dia \u00faltimo dia 24 de julho pelo governo estadual, o \u00faltimo relat\u00f3rio do Plano SP determina a perman\u00eancia do Vale do Para\u00edba, gerenciado pela DRS XVII (Taubat\u00e9), na fase 02, laranja, que permite o funcionamento com 20% da capacidade de atendimento presencial em escrit\u00f3rios em geral, imobili\u00e1rias, com\u00e9rcio de rua, shoppings e concession\u00e1rias. A abertura \u00e9 restrita a quatro horas di\u00e1rias, todos os dias, ou seis horas durante quatro dias e fechamento por outros tr\u00eas. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Em Lorena, o com\u00e9rcio funciona de segunda a sexta-feira, das 13h \u00e0s 17h, e aos s\u00e1bados, das 09h \u00e0s 13h. J\u00e1 o shopping funciona de segunda \u00e0 s\u00e1bado, das 16h \u00e0s 20h.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Prefeito F\u00e1bio Marcondes assinou nesta quinta-feira (30), o Decreto Municipal 7466\u00a0de 30 de julho 2020 que estende at\u00e9 10 de agosto o per\u00edodo de quarentena em preven\u00e7\u00e3o ao coronav\u00edrus. O decreto refor\u00e7a que n\u00e3o h\u00e1 nenhuma altera\u00e7\u00e3o nos par\u00e2metros de isolamento social e que estes seguem as decis\u00f5es do Plano SP. Divulgado no dia<\/p>\n<div class=\"read-more\"><a href=\"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/2020\/07\/30\/prefeitura-estende-quarentena-ate-10-de-agosto\/\" title=\"Read More\">Read More<\/a><\/div>\n","protected":false},"author":2,"featured_media":57565,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,19,128,70],"tags":[],"class_list":{"0":"post-57564","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-administracao","8":"category-comunicacao","9":"category-coronavirus","10":"category-destaques"},"_links":{"self":[{"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/posts\/57564"}],"collection":[{"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/comments?post=57564"}],"version-history":[{"count":2,"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/posts\/57564\/revisions"}],"predecessor-version":[{"id":57568,"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/posts\/57564\/revisions\/57568"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/media\/57565"}],"wp:attachment":[{"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/media?parent=57564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/categories?post=57564"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/tags?post=57564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}