{"id":26528,"date":"2016-04-29T11:03:42","date_gmt":"2016-04-29T14:03:42","guid":{"rendered":"http:\/\/www.lorena.sp.gov.br\/wordpress\/?p=26528"},"modified":"2016-04-29T11:03:42","modified_gmt":"2016-04-29T14:03:42","slug":"seja-voluntario-da-defesa-civil-de-lorena","status":"publish","type":"post","link":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/2016\/04\/29\/seja-voluntario-da-defesa-civil-de-lorena\/","title":{"rendered":"Seja volunt\u00e1rio da Defesa Civil de Lorena"},"content":{"rendered":"<p><span style=\"color: #000000;\">A Defesa Civil de Lorena quer a participa\u00e7\u00e3o da comunidade nos trabalhos e atividades de preven\u00e7\u00e3o de riscos e de prepara\u00e7\u00e3o contra amea\u00e7as de desastres. Por isso, a coordenadoria municipal quer ampliar o corpo de volunt\u00e1rios da Defesa Civil. Para ser parte do grupo de volunt\u00e1rios \u00e9 necess\u00e1rio preencher alguns requisitos, como\u00a0 ser maior de 18 anos, ter boas condi\u00e7\u00f5es f\u00edsicas para trabalhos operacionais e ter disponibilidade para atendimentos emergenciais.<\/span><\/p>\n<p><span style=\"color: #000000;\">Os interessados em integrar o grupo de volunt\u00e1rios de Lorena poder\u00e3o comparecer na pr\u00f3xima segunda-feira, 02 de maio, \u00e0s 9h, na Secretaria Municipal de Seguran\u00e7a P\u00fablica, localizada na Pra\u00e7a Mal Mallet, s\/n\u00ba, pr\u00e9dio da antiga Rede Ferrovi\u00e1ria. Na ocasi\u00e3o, al\u00e9m do esclarecimento de d\u00favidas, haver\u00e1 o agendamento de uma capacita\u00e7\u00e3o aos interessados.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Sobre o voluntariado.<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">Quando entes p\u00fablicos, privados e a pr\u00f3pria comunidade est\u00e3o unidos para o bem comum, a sociedade se torna mais atenta para a preserva\u00e7\u00e3o do futuro e das gera\u00e7\u00f5es que est\u00e3o por vir. O voluntariado \u00e9 extremamente importante para a realiza\u00e7\u00e3o dos trabalhos da Defesa Civil.<\/span><\/p>\n<p><span style=\"color: #000000;\">A nova for\u00e7a municipal volunt\u00e1ria vai colaborar no socorro emergencial de pessoas que, inesperadamente, sofrem efeitos de chuvas intensas, ventos fortes, granizo, estiagem, frio, entre outros fen\u00f4menos meteorol\u00f3gicos ou desastres diversos. A participa\u00e7\u00e3o do volunt\u00e1rio \u00e9 muito importante para que seja poss\u00edvel, num esfor\u00e7o conjunto, aprimorar o trabalho de ajuda humanit\u00e1ria em prol da sociedade lorenense.<\/span><\/p>\n<p><span style=\"color: #000000;\">A Defesa Civil de Lorena, desenvolver\u00e1 junto ao cidad\u00e3o que doa seu tempo, trabalho e talento, de maneira espont\u00e2nea, o exerc\u00edcio do esp\u00edrito de caridade e solidariedade.<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Defesa Civil de Lorena quer a participa\u00e7\u00e3o da comunidade nos trabalhos e atividades de preven\u00e7\u00e3o de riscos e de prepara\u00e7\u00e3o contra amea\u00e7as de desastres. Por isso, a coordenadoria municipal quer ampliar o corpo de volunt\u00e1rios da Defesa Civil. Para ser parte do grupo de volunt\u00e1rios \u00e9 necess\u00e1rio preencher alguns requisitos, como\u00a0 ser maior de<\/p>\n<div class=\"read-more\"><a href=\"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/2016\/04\/29\/seja-voluntario-da-defesa-civil-de-lorena\/\" title=\"Read More\">Read More<\/a><\/div>\n","protected":false},"author":2,"featured_media":26534,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19,70,14],"tags":[],"class_list":{"0":"post-26528","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-comunicacao","8":"category-destaques","9":"category-secretaria-seguranca"},"_links":{"self":[{"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/posts\/26528"}],"collection":[{"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/comments?post=26528"}],"version-history":[{"count":0,"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/posts\/26528\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/media\/26534"}],"wp:attachment":[{"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/media?parent=26528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/categories?post=26528"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.lorena.sp.gov.br\/wordpress\/index.php\/wp-json\/wp\/v2\/tags?post=26528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}